{"id":1038,"date":"2024-04-22T11:01:45","date_gmt":"2024-04-22T10:01:45","guid":{"rendered":"https:\/\/tufarmaciavirtual.com\/blog\/?p=1038"},"modified":"2024-05-23T06:25:04","modified_gmt":"2024-05-23T05:25:04","slug":"viajar-con-ninos-lo-que-debes-llevar-en-el-botiquin","status":"publish","type":"post","link":"https:\/\/tufarmaciavirtual.com\/blog\/viajar-con-ninos-lo-que-debes-llevar-en-el-botiquin\/","title":{"rendered":"Viajar con ni\u00f1os: Lo que debes llevar en el botiqu\u00edn"},"content":{"rendered":"\n<p><strong>Viajar siempre es un placer. Pero todos sabemos que hacerlo con ni\u00f1os supone un extra de carga: ropa, pa\u00f1ales, juguetes, accesorios\u2026 Y algo que no debemos olvidar y que para nosotros es imprescindible es un botiqu\u00edn que cubra las necesidades espec\u00edficas de los m\u00e1s peque\u00f1os de la casa y que nos puede sacar de muchos apuros \ud83d\ude09 <\/strong><\/p>\n\n\n\n<p>Hacernos con un buen botiqu\u00edn para ni\u00f1os nos permite estar siempre preparados para cualquier tipo de situaci\u00f3n. El contenido de un botiqu\u00edn vacacional infantil<strong> variar\u00e1 dependiendo de muchos factores<\/strong>: el destino de las vacaciones (no es lo mismo viajar a Barcelona, que hacerlo a un pa\u00eds tropical o a uno en v\u00edas de desarrollo), las edades de los ni\u00f1os&#8230; <\/p>\n\n\n\n<p>De todas maneras siempre debes de tener los \u00abb\u00e1sicos\u00bb, aquellos que nunca pueden faltar cuando se viaja con ni\u00f1os y hoy <a href=\"https:\/\/tufarmaciavirtual.com\/\">os ense\u00f1amos cu\u00e1les son esos imprescindibles.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/tufarmaciavirtual.com\/blog\/wp-content\/uploads\/2024\/04\/que-llevar-en-el-botiquin-ninos.jpg\" alt=\"\" class=\"wp-image-1043\" style=\"width:623px;height:auto\" srcset=\"https:\/\/tufarmaciavirtual.com\/blog\/wp-content\/uploads\/2024\/04\/que-llevar-en-el-botiquin-ninos.jpg 1000w, https:\/\/tufarmaciavirtual.com\/blog\/wp-content\/uploads\/2024\/04\/que-llevar-en-el-botiquin-ninos-300x300.jpg 300w, https:\/\/tufarmaciavirtual.com\/blog\/wp-content\/uploads\/2024\/04\/que-llevar-en-el-botiquin-ninos-150x150.jpg 150w, https:\/\/tufarmaciavirtual.com\/blog\/wp-content\/uploads\/2024\/04\/que-llevar-en-el-botiquin-ninos-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color has-medium-font-size wp-elements-a5fa2f0d43c2099bd1abba623428854c\"><strong>B\u00c1SICOS EN EL BOTIQU\u00cdN INFANTIL<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Antis\u00e9pticos:<\/strong>\u00a0\u00a0Combaten y previenen infecciones en caso de heridas, quemaduras o picaduras.\u00a0<\/li>\n\n\n\n<li><strong>Analg\u00e9sicos<\/strong>: Sirven para aliviar y reducir el dolor, como el dolor de cabeza, de garganta, muscular\u2026<\/li>\n\n\n\n<li><strong>Antipir\u00e9ticos:<\/strong>\u00a0Los antipir\u00e9ticos como el Dalsy o el Apiretal, ayudan a bajar la fiebre en el caso de que esta se presente debido a cualquier infecci\u00f3n.<\/li>\n\n\n\n<li><strong>Antihistam\u00ednicos:<\/strong>\u00a0Fundamentales en el caso de que nuestro hijo sufra alg\u00fan tipo de alergia.<\/li>\n\n\n\n<li><strong>Material de curaci\u00f3n:<\/strong>\u00a0Las heridas en los ni\u00f1os son frecuentes, por ello debemos tener siempre a mano gasas, esparadrapo, tiritas, vendas y algod\u00f3n. Este tipo de material tambi\u00e9n nos permite detener una hemorragia.<\/li>\n\n\n\n<li><strong>Instrumental:<\/strong>\u00a0Tijeras, pinzas y un term\u00f3metro son indispensables en cualquier botiqu\u00edn.<\/li>\n\n\n\n<li><strong>Suero fisiol\u00f3gico en monodosis:<\/strong>\u00a0Nos permite limpiar bien las heridas antes de aplicar el antis\u00e9ptico. Tambi\u00e9n podemos utilizarlo para limpiar los ojos o las fosas nasales.<\/li>\n\n\n\n<li><strong>Repelente de insectos:<\/strong>\u00a0El repelente evitar\u00e1 que nuestros hijos sean v\u00edctimas de las picaduras de diversas especies de insectos.<\/li>\n\n\n\n<li><strong>Crema con corticoides<\/strong>: Para tratar cualquier picadura de insecto as\u00ed como eczemas o cualquier reacci\u00f3n al\u00e9rgica en la piel.<\/li>\n\n\n\n<li><strong>Antidiarreicos:<\/strong>\u00a0Espec\u00edficos para ni\u00f1os. Son muy \u00fatiles para frenar la diarrea.<\/li>\n\n\n\n<li><strong>Sobres de rehidrataci\u00f3n:<\/strong>\u00a0Para restaurar la flora intestinal en caso de diarrea.<\/li>\n\n\n\n<li><strong>Crema o roll on para golpes y\/o moratones:<\/strong>\u00a0Un preparado a base de \u00e1rnica nos puede ser muy \u00fatil en caso de alg\u00fan golpe, contusi\u00f3n o moratones.<\/li>\n\n\n\n<li><strong>Protector solar:<\/strong>\u00a0Vayamos donde vayamos, sea cual sea la \u00e9poca del a\u00f1o, un protector solar es imprescindible y m\u00e1s teniendo en cuenta la piel sensible de los ni\u00f1os.<\/li>\n\n\n\n<li><strong>Cicalfate o similar<\/strong>:\u00a0<a href=\"https:\/\/tufarmaciavirtual.com\/productSearch?term=cicalfate\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#4c96c9\" class=\"has-inline-color\">Cicalfate<\/mark><\/a>\u00a0es una crema que ya hemos hablado en m\u00e1s de una ocasi\u00f3n. Sirve para restaurar la piel da\u00f1ada y tiene numerosas aplicaciones como quemaduras solares, quemaduras dom\u00e9sticas, heridas, rasgu\u00f1os y peque\u00f1os cortes, picaduras de insectos, eczemas, herpes labial, eritema del pa\u00f1al\u2026 entre otras. Un b\u00e1sico en cualquier botiqu\u00edn por su \u00abpoder\u00bb multifunci\u00f3n \ud83d\ude42<\/li>\n\n\n\n<li><strong>Antimareos:<\/strong>\u00a0Los ni\u00f1os a la hora de viajar se marean con mucha m\u00e1s frecuencia que los adultos; por ello llevar en nuestro botiqu\u00edn Biodramina o cualquier otro producto para tratar los mareos les puede hacer el viaje m\u00e1s llevadero a los ni\u00f1os.<\/li>\n\n\n\n<li><strong>Antibi\u00f3ticos de amplio espectro<\/strong>: Llevar en el botiqu\u00edn antibi\u00f3ticos se recomienda sobre todo si se viaja a alg\u00fan pa\u00eds en v\u00edas de desarrollo donde puede ser m\u00e1s dif\u00edcil conseguirlos en el caso de necesitarlos. Recordad que una correcta administraci\u00f3n de los antibi\u00f3ticos es fundamental para evitar la resistencia a este tipo de f\u00e1rmacos. Consultad a vuestro farmac\u00e9utico y utilizarlos s\u00f3lo si es realmente necesario.<\/li>\n<\/ul>\n\n\n\n<p><strong>IMPORTANTE:<\/strong> Recordad que la automedicaci\u00f3n conlleva un riesgo y a\u00fan m\u00e1s en el caso de los ni\u00f1os. Por ello ante cualquier duda sobre la medicaci\u00f3n que deb\u00e9is llevar encima para los m\u00e1s peques pedir informaci\u00f3n a vuestro m\u00e9dico o <a href=\"https:\/\/tufarmaciavirtual.com\/\">farmac\u00e9utico <\/a>que os informar\u00e1 de las indicaciones y de la administraci\u00f3n correcta para cada uno de ellos.<\/p>\n\n\n\n<p>Y sobre todo, <strong>no olvid\u00e9is incluir cualquier medicaci\u00f3n habitual que ya tenga prescrita vuestro hijo<\/strong>.<\/p>\n\n\n\n<p>Si ten\u00e9is cualquier duda, d\u00e9janosla en comentarios y te la responderemos encantados \ud83d\ude09<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viajar siempre es un placer. Pero todos sabemos que hacerlo con ni\u00f1os supone un extra de carga: ropa, pa\u00f1ales, juguetes, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[50,57,58],"tags":[152,153,157,155,132,93,154,156],"class_list":["post-1038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-botiquin","category-cuidado-infantil","category-viajeros","tag-botiquin","tag-botiquin-infantil","tag-consejos-para-viajar-con-ninos","tag-cuidado-infantil","tag-farmacia","tag-farmacia-andorra","tag-viajar-con-ninos","tag-viajes-en-familia"],"_links":{"self":[{"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/posts\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":7,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/posts\/1038\/revisions"}],"predecessor-version":[{"id":1047,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/posts\/1038\/revisions\/1047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/categories?post=1038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tufarmaciavirtual.com\/blog\/wp-json\/wp\/v2\/tags?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}